{"id":74059,"date":"2026-05-13T18:23:11","date_gmt":"2026-05-13T16:23:11","guid":{"rendered":"https:\/\/imagazine.it\/home_desk\/?p=74059"},"modified":"2026-05-13T18:23:11","modified_gmt":"2026-05-13T16:23:11","slug":"melanoma-avanzato-progetto-triestino-per-cure-piu-mirate","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/melanoma-avanzato-progetto-triestino-per-cure-piu-mirate\/","title":{"rendered":"Melanoma avanzato: progetto triestino per cure pi\u00f9 mirate"},"content":{"rendered":"<h6>Il gruppo di ricerca<\/h6>\n<p>&nbsp;<\/p>\n<p>TRIESTE \u2013 Seguire l\u2019evoluzione del melanoma cutaneo avanzato attraverso un semplice prelievo di sangue o un campione di urine, per ottenere informazioni utili a personalizzare le terapie e renderle meno invasive per i pazienti.<\/p>\n<p>\u00c8 questo l\u2019obiettivo di <strong><em>EXOMEL<\/em><\/strong>, il nuovo progetto di ricerca coordinato dall\u2019<strong>Universit\u00e0 di Trieste<\/strong>, che studier\u00e0 l\u2019impiego della <strong>biopsia liquida<\/strong> nel monitoraggio di una forma tumorale in cui la possibilit\u00e0 di osservare con precisione l\u2019andamento della malattia pu\u00f2 incidere in modo significativo sulle scelte terapeutiche.<\/p>\n<p>Il progetto, intitolato \u201c<em>MicroRNA esosomiale da biopsia liquida per il monitoraggio e la personalizzazione dei trattamenti del melanoma cutaneo avanzato<\/em>\u201d, punta a sviluppare e validare tecnologie diagnostiche innovative, condivise tra i centri clinici coinvolti, per rendere le cure sempre pi\u00f9 mirate, efficaci e adattate alle caratteristiche di ciascun paziente.<\/p>\n<p>L\u2019elemento pi\u00f9 innovativo riguarda l\u2019impiego del campione urinario come forma di biopsia liquida: <em>EXOMEL<\/em> studier\u00e0 infatti gli esosomi, piccole vescicole coinvolte nella comunicazione tra le cellule, e i microRNA che trasportano, con l\u2019obiettivo di individuare una combinazione di segnali biologici utile a distinguere i pazienti che rispondono all\u2019immunoterapia da quelli che non rispondono.<\/p>\n<p>EXOMEL \u00e8 finanziato dal <strong>Programma di cooperazione transfrontaliera Italia\u2013Austria Interreg VI-A 2021\u20132027<\/strong>, con il sostegno del Fondo Europeo di Sviluppo Regionale (FESR), per un importo complessivo pari a 572.055,59 euro.<\/p>\n<p>Il progetto, che si concluder\u00e0 il 31 marzo 2028, conferma il valore della cooperazione internazionale nella ricerca oncologica, mettendo in rete istituzioni sanitarie, universit\u00e0 e competenze tecnologiche italiane e austriache.<\/p>\n<p>L\u2019Universit\u00e0 di Trieste svolge il ruolo di <strong>capofila<\/strong> e coordina le attivit\u00e0 progettuali attraverso il <strong>Dipartimento di Scienze Mediche, Chirurgiche e della Salute<\/strong>, che impegna un gruppo di ricerca composto da<strong> Serena Bonin<\/strong>,<strong> Iris Zalaudek<\/strong>,<strong> Ilaria Gandin <\/strong>e<strong> Gabriele Grassi.<\/strong><\/p>\n<p>Il partenariato coinvolge anche l\u2019Azienda Sanitaria dell\u2019Alto Adige con gli ospedali di Brunico e Bolzano, una piccola e media impresa italiana e la Clinica universitaria di Dermatologia e Allergologia dell\u2019Universit\u00e0 Paracelsus di Salisburgo.<\/p>\n<p>\u201cAl centro di EXOMEL \u2013 spiega <strong>Serena Bonin<\/strong>, docente di Scienze tecniche di Medicina di Laboratorio dell\u2019Universit\u00e0 di Trieste e principal investigator del progetto \u2013 c\u2019\u00e8 lo sviluppo e la validazione della biopsia liquida, un approccio diagnostico che permette di ottenere informazioni rilevanti sulla malattia attraverso campioni biologici semplici da raccogliere, come sangue o urine. Oggi la biopsia liquida plasmatica \u00e8 impiegata soprattutto in ambito di ricerca per rilevare il DNA libero circolante tumorale, cio\u00e8 DNA con mutazioni specifiche del tumore. Questo approccio, per\u00f2, richiede che le mutazioni da monitorare siano note. Con EXOMEL vogliamo invece studiare i microRNA contenuti negli esosomi, vescicole attraverso cui le cellule comunicano tra loro, per verificare se una loro combinazione possa aiutare a discriminare i pazienti con melanoma cutaneo avanzato che rispondono all\u2019immunoterapia da quelli che non rispondono\u201d.<\/p>\n<p>\u201cAl momento \u2013 aggiunge Bonin \u2013 non sono disponibili biomarcatori predittivi utilizzati nella pratica ospedaliera per orientare in modo sistematico queste scelte terapeutiche. Per questo l\u2019obiettivo del progetto \u00e8 contribuire allo sviluppo di strumenti pi\u00f9 accessibili, ripetibili e potenzialmente utili nella personalizzazione dei trattamenti\u201d.<\/p>\n<p>Nel corso del progetto, la tecnologia della biopsia liquida sar\u00e0 estesa allo studio dei campioni urinari e applicata nei centri clinici coinvolti attraverso lo sviluppo di protocolli comuni e standardizzati. Questo passaggio consentir\u00e0 di verificare la solidit\u00e0 dell\u2019approccio in contesti clinici diversi, armonizzare le pratiche diagnostiche tra le strutture sanitarie partner e favorire la costruzione di una rete stabile di collaborazione tra Italia e Austria.<\/p>\n<p>I risultati attesi potranno avere ricadute anche oltre l\u2019ambito strettamente accademico e clinico. EXOMEL potr\u00e0 infatti contribuire allo sviluppo di nuovi strumenti diagnostici basati sulla biopsia liquida, aprendo possibili prospettive di trasferimento tecnologico e di valorizzazione industriale della ricerca, anche attraverso l\u2019interesse di imprese attive nel settore biomedicale e diagnostico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coordinato dall\u2019Universit\u00e0, studier\u00e0 l\u2019uso della biopsia liquida per monitorare l\u2019evoluzione della malattia e personalizzare i trattamenti in modo meno invasivo<\/p>\n","protected":false},"author":28,"featured_media":74060,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"dwc-title":[""],"dwc-content":[""],"footnotes":""},"categories":[5,79],"tags":[98,97,65,389,388],"class_list":["post-74059","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-attualita","category-attualita-prima-pagina","tag-ricerca","tag-salute","tag-trieste","tag-units","tag-universita","post_format-post-format-image"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura.jpg",1366,809,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura.jpg",1366,809,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura.jpg",1366,809,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-150x150.jpg",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-300x178.jpg",300,178,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-1024x606.jpg",640,379,true],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-474x324.jpg",474,324,true],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-391x260.jpg",391,260,true],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-300x400.jpg",300,400,true],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura.jpg",1366,809,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura.jpg",1366,809,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-1280x720.jpg",1280,720,true],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-1024x606.jpg",1024,606,true],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-720x380.jpg",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-250x210.jpg",250,210,true],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2026\/05\/melanoma-cura-272x182.jpg",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/attualita\/\" rel=\"category tag\">ATTUALIT\u00c0<\/a> <a href=\"https:\/\/imagazine.it\/home_desk\/category\/prima-pagina\/attualita-prima-pagina\/\" rel=\"category tag\">ATTUALIT\u00c0, PRIMA PAGINA<\/a>","rttpg_excerpt":"Coordinato dall\u2019Universit\u00e0, studier\u00e0 l\u2019uso della biopsia liquida per monitorare l\u2019evoluzione della malattia e personalizzare i trattamenti in modo meno invasivo","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/74059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=74059"}],"version-history":[{"count":1,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/74059\/revisions"}],"predecessor-version":[{"id":74061,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/74059\/revisions\/74061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/74060"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=74059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=74059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=74059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}