{"id":56436,"date":"2024-06-18T15:30:27","date_gmt":"2024-06-18T13:30:27","guid":{"rendered":"https:\/\/imagazine.it\/home_desk\/?p=56436"},"modified":"2024-06-19T15:15:10","modified_gmt":"2024-06-19T13:15:10","slug":"un-ascensore-panoramico-virtuale-per-vedere-palmanova-dallalto","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/un-ascensore-panoramico-virtuale-per-vedere-palmanova-dallalto\/","title":{"rendered":"Un ascensore panoramico virtuale per vedere Palmanova dall\u2019alto"},"content":{"rendered":"<p><span style=\"font-size: 10pt;\"><em>Piazza Grande a Palmanova (ph. Comune di Palmanova)<\/em><\/span><\/p>\n<p>PALMANOVA \u2013 Una<strong> cabina in cui simulare un ascensore virtuale<\/strong>, per rendere possibile a tutti i turisti la visione dal cielo della cinta muraria a forma di stella, architettura che le \u00e8 valsa l\u2019inserimento tra i beni mondiali patrimonio dell\u2019Umanit\u00e0 UNESCO.<\/p>\n<p>Questo l\u2019obiettivo del progetto <strong>&#8220;<em>Virtualift<\/em>&#8221; <\/strong>voluto dal<strong> Comune di Palmanova<\/strong>.<\/p>\n<p>Attraverso l&#8217;installazione di <strong>schermi LED a elevata luminosit\u00e0<\/strong> disposti ai lati e sul pavimento della cabina, verr\u00e0 <strong>riprodotto il movimento di un ascensore panoramico<\/strong>, dal punto di ingresso reale fino al cielo, dove sar\u00e0 possibile osservare la citt\u00e0 stellata.<\/p>\n<p>Chiuse le porte dell\u2019ascensore, sar\u00e0 possibile, attraverso una pulsantiera, selezionare l\u2019altezza virtuale da raggiungere per poi venire trasportati, attraverso i video presenti, in un <strong>viaggio fatto di sensazioni, immagini e suoni<\/strong>.<\/p>\n<p>Il Comune ha partecipato al bando regionale per l\u2019attuazione dei Programmi regionali attuativi del FESR,\u00a0<strong>ottenendo un finanziamento europeo da 100.000 euro<\/strong>\u00a0per la realizzazione dell\u2019opera che permetter\u00e0 ai visitatori di vivere l&#8217;esperienza di un vero e proprio ascensore panoramico per la visualizzazione dall&#8217;alto della citt\u00e0 di Palmanova.<\/p>\n<p>Il progetto ha ottenuto un punteggio di 94, assicurandosi il primo posto tra le progettualit\u00e0 presentate a valere sul bando.<\/p>\n<h3>Il ruolo della Camera di Commercio<\/h3>\n<p>L\u2019idea \u00e8 stata messa a fuoco durante un incontro con il\u00a0presidente della Camera di Commercio<strong> Giovanni Da Pozzo <\/strong>e il consigliere camerale<strong> Alessandro Tollon<\/strong>\u00a0a Palmanova per lanciare un progetto innovativo che guardi al turismo del futuro.<\/p>\n<p>La Camera di Commercio Pordenone-Udine, che sta collaborando con il Comune di Palmanova nell\u2019ideazione e realizzazione dell\u2019ascensore virtuale, ha deliberato un\u00a0<strong>contributo di 10.000 euro a copertura delle spese per l\u2019idea progettuale dell\u2019infrastruttura tecnologica<\/strong>.<\/p>\n<p>L&#8217;ente camerale, peraltro, da oltre un decennio, \u00e8 tra i protagonisti di Mirabilia, la rete fra le Cciaa italiane che ospitano siti Unesco e collabora attivamente per lo sviluppo di iniziative per valorizzarne al meglio le economie e lo sviluppo.<\/p>\n<p>Il Virtualift \u00e8 un concentrato di tecnologia:\u00a0<strong>schermi LED ad alta definizione, simulatori dinamici, effetti sonori<\/strong>. Il visitatore sar\u00e0 immerso in una esperienza unica, senza l\u2019ausilio di alcun tipo di dispositivo. I video saranno integrati con infografica ed effetti speciali, in modo da fornire al visitatore ulteriori informazioni (turistiche, storiche o altro).<\/p>\n<p>Sar\u00e0 poi possibile implementare l&#8217;esperienza con ulteriori contenuti video (come volo sulla citt\u00e0, visione notturna, viaggi nel tempo, immagini satellitari e altro), selezionabili da una classica pulsantiera di ascensore.<\/p>\n<h3>Accessibile a tutti<\/h3>\n<p>\u201cSorvolare Palmanova in elicottero o in mongolfiera \u2013 spiega il sindaco\u00a0<strong>Giuseppe Tellini<\/strong> \u2013 resta un\u2019esperienza unica ma limitata a pochi e condizionata da molte difficolt\u00e0 gestionali. Questa \u00e8 un\u2019ottima soluzione per vivere un\u2019esperienza quanto pi\u00f9 vicina a quella autentica\u201d.<\/p>\n<p>\u201cRingraziamo la Camera di Commercio Pordenone-Udine per averci stimolato e sostenuto in questo progetto unico al mondo. Il <em>Virtual lift<\/em> \u2013 aggiunge <strong>Silvia Savi<\/strong>, assessore comunale a cultura e turismo \u2013 amplia il target dei visitatori del sito Unesco di Palmanova\u00a0rendendo inclusiva l&#8217;esperienza della vista della citt\u00e0 stellata anche ai disabili, alle persone con ridotte capacit\u00e0 motorie o sensoriali e a tutti i visitatori che per vari motivi sono solitamente esclusi dai percorsi di visita sulla cinta bastionata. La fruizione della Fortezza sar\u00e0 completamente rivoluzionata, permettendo un\u2019innovativa comprensione delle sue forme e strutture, nonch\u00e9 dando la possibilit\u00e0 ai turisti, anche in poco tempo e con limitati spostamenti, di apprezzarne struttura e forma\u201d.<\/p>\n<p>L\u2019ascensore virtuale sar\u00e0 <strong>collocato nel giardino del Museo Civico<\/strong> e messo <strong>a sistema con la Sala Multimediale<\/strong> aperta da gennaio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finanziato il progetto &#8220;Virtualift&#8221;. Una cabina esperienziale per mostrare a tutti la citt\u00e0 stellata. Anche alle persone con disabilit\u00e0<\/p>\n","protected":false},"author":28,"featured_media":56437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"dwc-title":[""],"dwc-content":[""],"footnotes":""},"categories":[8],"tags":[960,2053,154,976,2054],"class_list":["post-56436","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-turismo","tag-accessibilita","tag-ascensore","tag-palmanova","tag-tecnologia","tag-virtuale","post_format-post-format-image"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore.jpg",1366,808,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore.jpg",1366,808,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore.jpg",1366,808,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-150x150.jpg",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-300x177.jpg",300,177,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-1024x606.jpg",640,379,true],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-474x324.jpg",474,324,true],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-391x260.jpg",391,260,true],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-300x400.jpg",300,400,true],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore.jpg",1366,808,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore.jpg",1366,808,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-1280x720.jpg",1280,720,true],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-1024x606.jpg",1024,606,true],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-720x380.jpg",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-250x210.jpg",250,210,true],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/06\/Piazza-Grande-Comune-di-PalmanovaAscensore-272x182.jpg",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/turismo\/\" rel=\"category tag\">TURISMO<\/a>","rttpg_excerpt":"Finanziato il progetto \"Virtualift\". Una cabina esperienziale per mostrare a tutti la citt\u00e0 stellata. Anche alle persone con disabilit\u00e0","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/56436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=56436"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/56436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/56437"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=56436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=56436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=56436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}