{"id":54408,"date":"2024-04-30T11:48:55","date_gmt":"2024-04-30T09:48:55","guid":{"rendered":"https:\/\/imagazine.it\/home_desk\/?p=54408"},"modified":"2024-04-30T11:50:15","modified_gmt":"2024-04-30T09:50:15","slug":"ripartono-da-staranzano-le-musiche-di-sconfine","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/ripartono-da-staranzano-le-musiche-di-sconfine\/","title":{"rendered":"Ripartono da Staranzano le Musiche di Sconfine"},"content":{"rendered":"<p><span style=\"font-size: 10pt;\"><em>I protagonisti del laboratorio musicale della Cooperativa Thiel<\/em><\/span><\/p>\n<p>STARANZANO &#8211; Parte in maggio la <strong>XV edizione di LIVE-Musiche di Sconfine<\/strong>. Il Festival transfrontaliero organizzato dal <strong>Gruppo Area di Ricerca DobiaLab<\/strong> e che d\u00e0 voce ai <strong>giovani artisti emergenti<\/strong> del Friuli Venezia Giulia e della vicina Slovenia.<\/p>\n<p>In vista di GO!2025, Gorizia e Nova Gorica Capitali della Cultura 2025, l\u2019obiettivo \u00e8 quello di favorire ulteriormente lo scambio fra due nazioni con <strong>concerti di band<\/strong>, <strong>dj set<\/strong> e <strong>laboratori<\/strong> che attraverso il linguaggio universale della musica possono <strong>abbattere barriere<\/strong> e unire due culture vicine non solo geograficamente. La XV edizione si articola in <strong>sette appuntamenti tra maggio e luglio<\/strong> in provincia di Gorizia a <strong>Staranzano<\/strong> e <strong>Sagrado<\/strong>, a <strong>Colloredo di Monte Albano<\/strong> in provincia di Udine e in Slovenia a <strong>Nova Gorica<\/strong> e <strong>Tolmin<\/strong>.<\/p>\n<p>Il programma \u00e8 variegato e lascia lo spazio a <strong>diversi generi musicali<\/strong>, in alcune occasioni accompagnati da ulteriori proposte di intrattenimento quali arti visive, videoproiezioni e danza. Le prime date sono il <strong>3 maggio a Staranzano<\/strong> nella <strong>sede di DobiaLab<\/strong> e il <strong>4 maggio<\/strong> nell\u2019<strong>Azienda Agricola Giuseppe Maggiori <\/strong>a <strong>Pissignano di<\/strong> <strong>Colloredo di Monte Albano<\/strong>. Il Festival transfrontaliero di DobiaLab ha ricevuto il sostegno di <strong>Giovani FVG<\/strong>, della <strong>Regione Friuli Venezia Giulia<\/strong>, della <strong>Fondazione Carigo<\/strong> e del <strong>Comune di Staranzano<\/strong>.<\/p>\n<p>Live Musiche di Sconfine ha coinvolto quest\u2019anno alcuni giovani seguiti dalla <strong>cooperativa sociale Thiel di Gorizia<\/strong> e per i propri <strong>punti ristoro<\/strong> ha abbracciato i progetti sociali della <strong>Comunit\u00e0 di Sant\u2019Osvaldo<\/strong> <strong>di Udine<\/strong> del \u201cBar Sport\u201d e la produzione del vino \u201cPrimo Passo\u201d promossa dall\u2019Azienda Agricola Giuseppe Maggiori.<\/p>\n<p>Si partir\u00e0 quindi <strong>venerd\u00ec 3 maggio<\/strong> nella sede di DobiaLab <strong>alle 18<\/strong> con \u00ab<strong>Watta e gli Oltrebeats<\/strong>\u00bb, esibizione nata da un <strong>laboratorio di musica digitale inclusivo<\/strong> condotto da <strong>Walter \u201cwattabass\u201d Sguazzin<\/strong>, formatore certificato dal 2018 di Ableton, una societ\u00e0 tedesca che produce e distribuisce software con programmi di produzione ed esecuzione musicale.<\/p>\n<p>Nella performance verr\u00e0 utilizzato in particolare il controller midi Push e Ableton Live 12 per creare musica, oltre ai software Melodics e Kontact per elaborare idee. Il laboratorio e l\u2019esibizione finale sono stati realizzati in collaborazione con la <strong>cooperativa sociale Thiel<\/strong> da sempre impegnata in percorsi d&#8217;integrazione per persone fragili.<\/p>\n<p>I protagonisti saranno quindi <strong>sette ragazzi<\/strong> seguiti dalla cooperativa che il 3 maggio faranno sentire <strong>le basi musicali che hanno composto<\/strong> e su cui canteranno una canzone scritta sempre da loro. Grazie a questa esperienza con Live Musiche di Sconfine i ragazzi non solo imparano a creare un prodotto musicale, ma hanno anche l\u2019opportunit\u00e0 di comprendere come si organizza un concerto, come si prepara il palco e altri aspetti del lavoro che c\u2019\u00e8 dietro il mondo dello spettacolo.<\/p>\n<p>Seguir\u00e0 poi <strong>alle 21<\/strong> il <strong>concerto dei Kavasutra<\/strong>, band di Nova Gorica. Prendendo spunto dal compositore, cantante e polistrumentista statunitense Frank Zappa, esplorano la loro creativit\u00e0 musicale spaziando <strong>dal jazz-rock al funk e alla psichedelia<\/strong> con le voci e le chitarre elettriche di <strong>Aik Vremec<\/strong> e <strong>Anton Lorenzutti<\/strong>, la voce e il basso elettrico di <strong>Timi Vremec<\/strong> e la batteria di <strong>Robi Erzeti<\/strong><strong>\u010d<\/strong>. Maliziosi con le parole ed esuberanti e frizzanti nella musica, sono maestri dell\u2019improvvisazione musicale e si divertono con giocosa facilit\u00e0 a mescolare tanti stili diversi, senza temere di mettere in discussione la propria salute mentale. Nel corso della serata il punto ristoro sar\u00e0 offerto dai ragazzi del \u201cBar Sport\u201d della Comunit\u00e0 Sant\u2019Osvaldo di Udine.<\/p>\n<figure id=\"attachment_54409\" aria-describedby=\"caption-attachment-54409\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-54409 size-full\" src=\"https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Sonica-Parresia.jpeg\" alt=\"Sonica Parresia\" width=\"1000\" height=\"630\" title=\"\" srcset=\"https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Sonica-Parresia.jpeg 1000w, https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Sonica-Parresia-300x189.jpeg 300w, https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Sonica-Parresia-768x484.jpeg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-54409\" class=\"wp-caption-text\">Sonica Parresia<\/figcaption><\/figure>\n<p>Il <strong>4 maggio<\/strong> invece ci si sposter\u00e0 all\u2019<strong>Azienda Agricola di Giuseppe Maggiori<\/strong> a <strong>Pissignano di Colloredo di Monte Albano<\/strong>. Si partir\u00e0 <strong>alle 17<\/strong> con il concerto dei <strong>Sonica Parresia<\/strong>, composto da <strong>Donatello Pisanello<\/strong> con l\u2019organetto diatonico e <strong>Carlo Mascolo<\/strong> con il trombone. Il duo trasforma <strong>in pratica musicale l\u2019arte della parresia<\/strong>, cio\u00e8 il <strong>diritto-dovere di dire la verit\u00e0<\/strong>.<\/p>\n<p>I due musicisti si fanno quindi portatori delle proprie verit\u00e0 maturate lungo il loro percorso artistico condividendo un vocabolario sonoro che attinge alla <strong>musica intuitiva e d\u2019improvvisazione<\/strong> e ad alcune sonorit\u00e0 mediterranee declinate nella contemporaneit\u00e0. Il risultato \u00e8 una performance sonora dove i colori sono timbri sempre nuovi, frutto di un processo continuo di ricerca di nuovi esiti e possibilit\u00e0 musicali.<\/p>\n<p>Seguir\u00e0 poi il <strong>concerto <\/strong><strong>Dobryda<\/strong>, ovvero una <strong>selezione musicale in vigna<\/strong> proposta da <strong>DobiaLab<\/strong> e da <strong>Hybrida<\/strong>, partner ventennale del Gruppo Area di Ricerca che si occupa di promozione di eventi e concerti. Nella location dell&#8217;Azienda Agricola Maggiori sar\u00e0 inoltre possibili unire l\u2019ascolto musicale alla degustazione di ottimi vini tra cui \u201c<strong>Primo Passo<\/strong>\u201d, un vino naturale prodotto grazie a un gruppo della comunit\u00e0 di Sant\u2019Osvaldo di Udine seguito dal vinaiolo Alessandro Franco.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esordio con il laboratorio musicale inclusivo realizzato dai giovani della cooperativa Thiel assieme a Walter Sguazzin e la band Kavasutra<\/p>\n","protected":false},"author":22,"featured_media":54411,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"dwc-title":[""],"dwc-content":[""],"footnotes":""},"categories":[37],"tags":[1730,885,55,1731,554],"class_list":["post-54408","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-cultura-e-spettacolo","tag-dobialab","tag-inclusione","tag-musica","tag-musiche-di-sconfine","tag-staranzano","post_format-post-format-image"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel.jpg",1366,719,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel.jpg",1366,719,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel.jpg",1366,719,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-150x150.jpg",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-300x158.jpg",300,158,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-1024x539.jpg",640,337,true],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-474x324.jpg",474,324,true],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-391x260.jpg",391,260,true],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-300x400.jpg",300,400,true],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel.jpg",1366,719,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel.jpg",1366,719,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-1280x719.jpg",1280,719,true],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-1024x539.jpg",1024,539,true],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-720x380.jpg",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel-250x210.jpg",250,210,true],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/04\/Gruppo-laboratorio-musicale-cooperativa-Thiel.jpg",272,143,false]},"rttpg_author":{"display_name":"Livio Nonis","author_link":"https:\/\/imagazine.it\/home_desk\/author\/nonis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/cultura-e-spettacolo\/\" rel=\"category tag\">CULTURA&amp;SPETTACOLO<\/a>","rttpg_excerpt":"Esordio con il laboratorio musicale inclusivo realizzato dai giovani della cooperativa Thiel assieme a Walter Sguazzin e la band Kavasutra","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/54408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=54408"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/54408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/54411"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=54408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=54408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=54408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}