{"id":53072,"date":"2024-03-25T11:09:34","date_gmt":"2024-03-25T10:09:34","guid":{"rendered":"https:\/\/imagazine.it\/home_desk\/?p=53072"},"modified":"2024-03-26T15:28:23","modified_gmt":"2024-03-26T14:28:23","slug":"patrimonio-culturale-e-tecnologie-immersive-il-mit-impara-dal-friuli","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/patrimonio-culturale-e-tecnologie-immersive-il-mit-impara-dal-friuli\/","title":{"rendered":"Patrimonio culturale e tecnologie immersive: il MIT impara dal Friuli"},"content":{"rendered":"<p>UDINE \u2013 Si consolida la collaborazione tra il <strong>Massachusetts institute of technology (Mit)<\/strong> di Cambridge (Massachusetts, Usa) e il <a href=\"https:\/\/storytellinglab.eu\/\" target=\"_blank\" rel=\"noopener\">Digital Storytelling Lab<\/a> dell\u2019<strong>Universit\u00e0<\/strong> <strong>di Udine<\/strong> che si occupa di narrazioni digitali e multimediali.<\/p>\n<p>Il laboratorio dell\u2019Ateneo friulano ha presentato il progetto \u201c<em>Sensing dolce vita<\/em>\u201d sulle tecnologie immersive nella valorizzazione e preservazione del patrimonio culturale al <a href=\"https:\/\/act.mit.edu\" target=\"_blank\" rel=\"noopener\">Mit List Visual Arts Center<\/a>, il media lab dell\u2019universit\u00e0 americana.<\/p>\n<p>Il progetto spazia tra ricerca d\u2019archivio, storia del cinema e storytelling multimediale. Nell\u2019occasione \u00e8 stato anche mostrato l\u2019ultimo aggiornamento della app di realt\u00e0 virtuale che ricostruisce l\u2019esperienza di uno spettatore all\u2019interno del Cinema Odeon di Udine nel 1939.<\/p>\n<p>La visita \u00e8 servita inoltre a illustrare il polo Media Lab, la nuova realt\u00e0 laboratoriale in fase di realizzazione all\u2019Uniud Lab Village, ispirato proprio al centro di ricerca del Mit.<\/p>\n<p>Il Digital storytelling lab, del Dipartimento di studi umanistici e del patrimonio culturale, fa attivit\u00e0 di ricerca, didattiche e di produzione nei settori delle narrazioni digitali e multimediali e dell\u2019educazione ai media.<\/p>\n<p>La missione era composta dal responsabile progetti del laboratorio, <strong>Andrea Mariani<\/strong>, e dal tecnico <strong>Giacomo Vidoni<\/strong>. La visita rientra in uno specifico programma di scambi tra Friuli Venezia Giulia e Mit finalizzato al potenziamento delle collaborazioni internazionali in tema di ricerca, innovazione a trasferimento tecnologico.<\/p>\n<h3><strong>Cinque anni di collaborazioni <\/strong><\/h3>\n<p>\u00c8 iniziato nel 2019 il rapporto del Digital Storytelling Lab con il Mit List Visual Arts Center e, in particolare, con il professor Gediminas Urbonas. Nel 2021, la prima missione negli Stati Uniti ha favorito, in particolare, lo sviluppo della app che riproduce l\u2019esperienza di uno spettatore all\u2019Odeon di Udine. L\u2019ultimo aggiornamento \u00e8 stato realizzato con la visual artist milanese <strong>Eleonora Roaro<\/strong>, i 3D designer <strong>Alessandro Passoni<\/strong> e <strong>Saul Clemente<\/strong> e il sound designer <strong>Emiliano Bagnato<\/strong>.<\/p>\n<p>Oltre ad Andrea Mariani e Giacomo Vidoni, il gruppo di lavoro del laboratorio coinvolto nel programma di scambio include il direttore tecnico del DSL <strong>Gianandrea Sasso<\/strong>, e i dottorandi di Cinema <strong>Alexander Edwards <\/strong>e <strong>Steven Stergar<\/strong>.<\/p>\n<h3><strong>Il Digital Storytelling Lab<\/strong><\/h3>\n<p>Il laboratorio \u00e8 uno spazio di sperimentazione, aggregazione e formazione. Favorisce il pensiero creativo, le modalit\u00e0 formative laboratoriali e cooperative ed \u00e8 una risorsa territoriale per l\u2019apprendimento, per la comunicazione e per l\u2019innovazione creativa e sostenibile. Il progetto Digital Storytelling Lab ha vinto un bando dell\u2019allora Ministero dell\u2019istruzione, dell\u2019universit\u00e0 e della ricerca sui \u201claboratori territoriali per l\u2019occupabilit\u00e0\u201d.<\/p>\n<p>Il progetto ha visto la partecipazione di una rete di scuole di Udine e del territorio coordinate dal Liceo classico \u201cIacopo Stellini\u201d, dall\u2019Ateneo e da associazioni di categoria, istituzioni culturali e imprese.<\/p>\n<p>L\u2019offerta formativa di corsi e seminari identifica la prima missione del laboratorio. Si rivolge agli studenti delle scuole secondarie di primo e secondo grado, dei corsi di laurea triennale e magistrale e a tutti gli interessati a ottenere la certificazione StarT necessaria alla richiesta di prestito delle attrezzature.<\/p>\n<p>La missione produttiva del laboratorio si presenta come una piattaforma dinamica e un incubatore creativo. Vengono valutati specifici progetti di collaborazioni, proposte di <em>work experience<\/em>, pianificazione e consulenze su attrezzatura e know-how. L\u2019attenzione \u00e8 rivolta a tutte quelle iniziative del territorio che sorgono dalle realt\u00e0 scolastiche, dal mondo dell\u2019imprenditoria e dalle imprese creative e artistiche indipendenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Digital Storytelling Lab dell&#8217;Universit\u00e0 di Udine in missione in Massachusetts. Illustrato anche l\u2019ultimo aggiornamento della app di realt\u00e0 virtuale che ricostruisce l\u2019esperienza di uno spettatore all\u2019interno del Cinema Odeon di Udine nel 1939<\/p>\n","protected":false},"author":28,"featured_media":53073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"dwc-title":[""],"dwc-content":[""],"footnotes":""},"categories":[6],"tags":[1380,1381,98,101,206],"class_list":["post-53072","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-societa","tag-digitale","tag-mit","tag-ricerca","tag-udine","tag-uniud","post_format-post-format-image"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit.jpg",1366,784,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit.jpg",1366,784,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit.jpg",1366,784,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-150x150.jpg",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-300x172.jpg",300,172,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-1024x588.jpg",640,368,true],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-474x324.jpg",474,324,true],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-391x260.jpg",391,260,true],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-300x400.jpg",300,400,true],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit.jpg",1366,784,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit.jpg",1366,784,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-1280x720.jpg",1280,720,true],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-1024x588.jpg",1024,588,true],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-720x380.jpg",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit-250x210.jpg",250,210,true],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/03\/Presentazione-al-Mit.jpg",272,156,false]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/societa\/\" rel=\"category tag\">SOCIET\u00c0<\/a>","rttpg_excerpt":"Il Digital Storytelling Lab dell'Universit\u00e0 di Udine in missione in Massachusetts. Illustrato anche l\u2019ultimo aggiornamento della app di realt\u00e0 virtuale che ricostruisce l\u2019esperienza di uno spettatore all\u2019interno del Cinema Odeon di Udine nel 1939","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/53072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=53072"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/53072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/53073"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=53072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=53072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=53072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}