{"id":51874,"date":"2024-02-27T12:53:59","date_gmt":"2024-02-27T11:53:59","guid":{"rendered":"https:\/\/imagazine.it\/home_desk\/?p=51874"},"modified":"2024-02-28T11:18:43","modified_gmt":"2024-02-28T10:18:43","slug":"riequilibrare-il-nostro-tempo-giornata-evento-a-udine","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/riequilibrare-il-nostro-tempo-giornata-evento-a-udine\/","title":{"rendered":"Riequilibrare il nostro tempo, giornata evento a Udine"},"content":{"rendered":"<p><em><span style=\"font-size: 10pt;\">Da sinistra De Marco, Venanzi e Marchiol<\/span><\/em><\/p>\n<p>UDINE \u2013 <strong>TEDx<\/strong> torna a Udine con un evento lungo un giorno per <strong>riflettere sui cambiamenti del nostro tempo<\/strong>, quelli gi\u00e0 in atto e quelli assolutamente necessari per riequilibrare il nostro presente e soprattutto quello delle future generazioni.<\/p>\n<p>L\u2019edizione 2024 \u00e8 stata presentata oggi alla Libreria Tarantola alla presenza del vicesindaco <strong>Alessandro Venanzi<\/strong> e dell\u2019assessore ai lavori pubblici e alla viabilit\u00e0 <strong>Ivano Marchiol<\/strong>.<\/p>\n<p><strong>Appuntamento sabato 9 marzo al Teatro Palamostre<\/strong> con <strong><em>Sbilanciati<\/em><\/strong>, tema dell\u2019edizione 2024: si parte dalla perdita di equilibrio del nostro tempo \u2013 nel lavoro, nell\u2019istruzione, nei rapporti economici, nelle relazioni, nella sostenibilit\u00e0 ambientale \u2013 per arrivare al necessario cambio di passo e di modelli per costruire un nuovo futuro.<\/p>\n<p>Entra in gioco il rapporto tra generazioni, quindi. Da un lato quella pi\u00f9 anziana che ha formato l\u2019Italia e il mondo sino ad oggi, cresciuta con un\u2019impronta che ora e nel futuro non sar\u00e0 pi\u00f9 sostenibile. Dall&#8217;altro, le generazioni pi\u00f9 giovani che non seguono pi\u00f9 quel modello, ne soffrono e agiscono in ordine sparso.<\/p>\n<p>Dalle 10 alle 18, suddivisi in quattro sessioni, saranno <strong>14 gli speaker<\/strong> a salire sul palco del Palamostre <strong>per 12 talk da 15 minuti ciascuno<\/strong>: nessuno speaker riceve compenso per la sua partecipazione, come da regole internazionali dei TEDx.<\/p>\n<p>Il tema dello sbilanciamento apre le porte a diversi argomenti che sono stati raggruppati in quattro categorie: modello economico, socio-politico, educativo e lavorativo. Ad ogni speaker \u00e8 stata posta <strong>una domanda secca a cui rispondere<\/strong> attraverso il proprio intervento: sul palco imprenditori, giornalisti, attivisti, scrittori, educatori, esperti di marketing e intelligenza artificiale.<\/p>\n<p>Per dare un assaggio, <strong>Enrico Foglia<\/strong>, esperto di marketing rigenerativo, presenter\u00e0 nuovi modelli per organizzazioni e istituzioni; <strong>Elvis Tusha<\/strong>, specializzato in intelligenza artificiale, parler\u00e0 di dialogo intergenerazionale; <strong>Luciano Canova<\/strong> parler\u00e0 di crisi della denatalit\u00e0, lavoro e nuove dimensioni del sistema previdenziali, o ancora la scrittrice <strong>Alli Beltrame<\/strong> analizzer\u00e0 l&#8217;ignoranza digitale e la poco educazione alle emozioni dei genitori dalla genZ in su, mentre tre giovani attivisti illustreranno perch\u00e9 la mobilitazione per il pianeta dovrebbe essere una priorit\u00e0 di tutti.<\/p>\n<p><em>\u201cL\u2019edizione 2024 del TEDx Udine <\/em>\u2013 spiega <strong>Eva De Marco<\/strong>, ideatrice e curatrice dell\u2019evento fin dalla prima edizione \u2013 <em>ha l\u2019obiettivo di ampliare il senso di comunit\u00e0:<\/em> <em>partendo dal titolo di quest\u2019anno e quindi da un senso di disagio trasversale alle generazioni, cerchiamo di portare sul palco non solo analisi, ma soluzioni, visioni concrete e tangibili per vivere il presente e per innescare un cambiamento condiviso dal basso, come comunit\u00e0 appunto. Essere sbilanciati deve diventare una consapevolezza da cui innescare una reazione, sia del singolo sia della collettivit\u00e0.\u201d<\/em><\/p>\n<p>Ad organizzare l\u2019evento, coordinati da De Marco, c\u2019 \u00e8 il team di TEDx Udine composto da pi\u00f9 di 20 persone, professionisti e volontari, tra cui tantissimi giovani e giovanissimi.<\/p>\n<h3><strong>La sostenibilit\u00e0: cibo, trasporti e materiali riciclabili<\/strong><\/h3>\n<p>TEDxUdine punta ad essere sempre pi\u00f9 sostenibile e ha gi\u00e0 avviato il percorso verso la certificazione <strong>ISO 20121, <\/strong>lo standard di gestione per l&#8217;organizzazione sostenibile degli eventi.<\/p>\n<p>Tutto il packaging del pranzo sar\u00e0 100% riciclato e compostabile e anche i biscotti serviti durante le pause Caff\u00e8 by Oro Caff\u00e8 sono confezionati in plastica di biomais (azienda Fortini).<\/p>\n<p>La <strong>Bike For The Future, <\/strong>posizionata fuori dal Palamostre, \u00e8 la bicicletta (donata dallo storico negozio Cicli Marino Rossi) che genera energia elettrica pulita attraverso la pedalata che servir\u00e0 per alimentare fonti luminose o ricaricare smartphone, verificando l\u2019energia generata attraverso una App.<\/p>\n<p>Anche la <strong>mobilit\u00e0<\/strong> da e per il Palamostre \u00e8 pi\u00f9 possibile sostenibile: grazie alla collaborazione con il <strong>Comune di Udine<\/strong> e alla partnership con <strong>Arriva Udine<\/strong>, sar\u00e0 attivo un servizio di navetta gratuito dal parcheggio del terminal studenti dove poter lasciare comodamente la propria auto e raggiungere il teatro senza il problema di trovare parcheggio nelle vicinanze (via Ampezzo sar\u00e0 chiusa al traffico durante l\u2019intera giornata).<\/p>\n<h3><strong>Il pranzo <\/strong><\/h3>\n<p>Il pranzo \u00e8 incluso nel prezzo del biglietto e verr\u00e0 consegnato ad ogni partecipante: il men\u00f9 \u00e8 una creazione di <strong>Natascha Noia<\/strong>, la giovane chef friulana che ha creato il progetto \u201cChef mobile\u201d, la chef a domicilio per privati, aziende, produzioni cinematografiche in tutta la regione. Il dolce invece sar\u00e0 del Laboratorio Del Dolce di Pagnacco.<\/p>\n<h3><strong>xGate<\/strong><\/h3>\n<p>Il portale di TEDx Udine, una grande \u201cx\u201d tridimensionale, \u00e8 posizionato in via Mercatovecchio, nel cuore del centro storico, per far conoscere l\u2019evento alla citt\u00e0.<\/p>\n<p>\u00c8 realizzata solo con materiali naturali come legno, stoffa e ferro e rigorosamente di recupero da materiali non pi\u00f9 utilizzabili per la produzione dalle aziende del territorio che hanno contribuito alla sua realizzazione (Mobili Giarle e RE49). Il portale riporta un QR code per accedere a tutti i contenuti di approfondimento all\u2019evento attraverso smartphone.<\/p>\n<h3><strong>Il teatro partecipato con CSS<\/strong><\/h3>\n<p>Sul palco del TEDx ci sar\u00e0 spazio anche per il teatro grazie alla collaborazione con CSS Teatro Stabile del Friuli Venezia Giulia che da oltre 20 anni sviluppa progetti di teatro partecipato con l\u2019obiettivo di proporre un laboratorio aperto alla cittadinanza, a gruppi artistici, a comunit\u00e0, associazioni culturali, facendo emergere consapevolezze attorno a tematiche ogni volta sempre diverse.<\/p>\n<p>Semplici cittadini tra i 25 e gli 85 anni porteranno in scena dei brevi monologhi per raccontare il proprio personale sbilanciamento rispetto al presente per un vero incontro e confronto tra generazioni.<\/p>\n<h3><strong>Biglietti<\/strong><\/h3>\n<p>I biglietti sono acquistabili online dal sito <a href=\"https:\/\/oooh.events\/evento\/tedxudine-sbilanciati-biglietti\/\" target=\"_blank\" rel=\"noopener\">https:\/\/oooh.events\/evento\/tedxudine-sbilanciati-biglietti\/<\/a> al costo di 45 euro per l\u2019intera giornata a teatro incluso il pranzo, prezzo speciale di 20 euro per i giovani fino a 25 anni e per i gruppi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sar\u00e0 &#8220;Sbilanci\u00e0ti&#8221; il teme di TEDx in programma sabato 9 marzo al Palamostre: alla ricerca di modelli per costruire un nuovo futuro<\/p>\n","protected":false},"author":28,"featured_media":51875,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"dwc-title":[""],"dwc-content":[""],"footnotes":""},"categories":[6],"tags":[922,923,924,921,101],"class_list":["post-51874","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-societa","tag-futuro","tag-sostenibilita","tag-stili-di-vita","tag-tedx","tag-udine","post_format-post-format-image"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3.jpg",1366,791,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3.jpg",1366,791,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3.jpg",1366,791,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-150x150.jpg",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-300x174.jpg",300,174,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-1024x593.jpg",640,371,true],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-300x300.jpg",300,300,true],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-500x500.jpg",500,500,true],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-474x324.jpg",474,324,true],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-391x260.jpg",391,260,true],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-300x400.jpg",300,400,true],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3.jpg",1366,791,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3.jpg",1366,791,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-1280x720.jpg",1280,720,true],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-1024x593.jpg",1024,593,true],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3-720x380.jpg",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3.jpg",250,145,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/tedxudine3.jpg",272,158,false]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/societa\/\" rel=\"category tag\">SOCIET\u00c0<\/a>","rttpg_excerpt":"Sar\u00e0 \"Sbilanci\u00e0ti\" il teme di TEDx in programma sabato 9 marzo al Palamostre: alla ricerca di modelli per costruire un nuovo futuro","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/51874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=51874"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/51874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/51875"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=51874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=51874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=51874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}