{"id":50323,"date":"2023-11-04T00:00:00","date_gmt":"2023-11-03T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/un-murale-spaziale-per-la-citta-stellata\/"},"modified":"2023-11-04T00:00:00","modified_gmt":"2023-11-03T23:00:00","slug":"un-murale-spaziale-per-la-citta-stellata","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/un-murale-spaziale-per-la-citta-stellata\/","title":{"rendered":"Un murale &#8220;spaziale&#8221; per la citt\u00e0 stellata"},"content":{"rendered":"<p> \tPALMANOVA \u2013 Inaugurato ufficialmente a Palmanova il <strong>murale realizzato per la \u201ccitt\u00e0 stellata\u201d<\/strong> al termine di un lavoro eseguito da Chiara, Eden, Gaia, Benedetta, Manuela, Ginevra, Jacopo e Angelo durante il Laboratorio di <em>street art<\/em> condotto da <strong>Michele Nardon<\/strong> nell\u2019ambito del progetto \u201c<em>Passo dopo passo. Palestre di inclusione #2<\/em>\u201d, promosso dalla cooperativa Thiel in partenariato con il Comune, l\u2019Asufc e il sostegno della Fondazione Friuli (Bando Welfare) e del Fondo Beneficenza di Intesa Sanpaolo.<\/p>\n<p> \tUn lavoro \u201cspaziale\u201d, con pianeti, stelle, costellazioni, un ufo che illumina Palmanova e un alieno che fa l&#8217;autostop per raggiungere la citt\u00e0 stellata, visibile e godibile sui muri del campetto di basket di Contrada Foscarini.<\/p>\n<p> \t\u00abIl tema \u00e8 nato dall\u2019idea che ciascuno poteva avere il proprio pianeta ed esprimere le proprie emozioni attraverso i colori, ma alla fine abbiamo lavorato tutti assieme: l\u2019intera opera \u00e8 il frutto di una collaborazione e il risultato si vede\u00bb, commenta Chiara, portavoce del gruppo con l\u2019aggiunta della sottolineatura di Jacopo: \u00abSarebbe bello completare l\u2019opera realizzando un murale anche sull\u2019altro lato del campetto, per rendere ancora pi\u00f9 bello un lavoro gi\u00e0 bello\u00bb.<\/p>\n<p> \t\u00abGrazie ai ragazzi del Laboratorio per aver reso pi\u00f9 colorato un luogo simbolo per i giovani di Palmanova. Grazie alla cooperativa sociale Thiel per aver creato questa opportunit\u00e0 creativa per i nostri ragazzi, aiutando l\u2019Amministrazione a offrire un&#8217;alternativa efficace all&#8217;isolamento e allo smartphone. I Laboratori del progetto &#8220;Passo dopo passo. Palestre l&#8217;inclusione&#8221; contribuiscono allo sviluppo della responsabilizzazione, della creativit\u00e0, dell\u2019innovazione, della partecipazione sociale, dell\u2019impegno volontario, della cittadinanza attiva e dell\u2019inclusione. Il progetto rispecchia a pieno il senso delle politiche giovanili: promuovere attivit\u00e0 di educazione non formale basate sulla partecipazione\u00a0volontaria\u00bb, ha affermato <strong>Thomas Trino<\/strong>, assessore comunale allo Sport, Giovani e Innovazione.<\/p>\n<p> \t\u00abCi teniamo a ringraziare le famiglie dei partecipanti per la fiducia e la collaborazione. Un grande grazie a Michele Nardon per aver assecondato la creativit\u00e0 dei ragazzi lasciandoli completamente liberi di esprimersi e sperimentarsi. Infine, un sentito ringraziamento all&#8217;Amministrazione comunale che ha creduto nel progetto concedendoci lo spazio e che, presenziando all&#8217;inaugurazione, ha testimoniato il valore dell&#8217;impegno dei ragazzi per la citt\u00e0\u00bb, sono state le parole di <strong>Anna Sabatti<\/strong>, referente del progetto e vicepresidente della cooperativa Thiel.<\/p>\n<p> \t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inaugurato a Palmanova il frutto del lavoro dei ragazzi del Laboratorio di street art organizzato dalla cooperativa Thiel<\/p>\n","protected":false},"author":28,"featured_media":50324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-50323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",1000,675,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",1000,675,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",1000,675,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1-300x203.webp",300,203,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",640,432,false],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1-300x300.webp",300,300,true],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1-500x500.webp",500,500,true],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1-474x324.webp",474,324,true],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1-391x260.webp",391,260,true],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1-300x400.webp",300,400,true],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",1000,675,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",1000,675,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",1000,675,false],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",1000,675,false],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",250,169,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/54985-1.webp",270,182,false]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/attualita\/\" rel=\"category tag\">ATTUALIT\u00c0<\/a>","rttpg_excerpt":"Inaugurato a Palmanova il frutto del lavoro dei ragazzi del Laboratorio di street art organizzato dalla cooperativa Thiel","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/50323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=50323"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/50323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/50324"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=50323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=50323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=50323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}