{"id":48099,"date":"2022-12-22T00:00:00","date_gmt":"2022-12-21T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/nuove-sinergie-per-valorizzare-le-aree-interne-del-fvg\/"},"modified":"2022-12-22T00:00:00","modified_gmt":"2022-12-21T23:00:00","slug":"nuove-sinergie-per-valorizzare-le-aree-interne-del-fvg","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/nuove-sinergie-per-valorizzare-le-aree-interne-del-fvg\/","title":{"rendered":"Nuove sinergie per valorizzare le aree interne del FVG"},"content":{"rendered":"<p> \tFavorire uno scambio generativo tra realt\u00e0 imprenditoriali innovative presenti nelle aree interne del Friuli Venezia Giulia e un gruppo di giovani formati e pronti a sperimentarsi come \u201cagenti di valorizzazione territoriale\u201d.<\/p>\n<p> \tQuesto l\u2019obiettivo della seconda edizione del progetto \u201c<strong><em>Percorsi spericolati<\/em><\/strong>\u201d promosso dalla <strong>Fondazione Pietro Pittini <\/strong>insieme ai partner Meraki-desideri culturali, Rob de Matt e grazie al supporto della Coop. Sociale Cramars, di Avanzi e della Rete Rifai.<\/p>\n<p> \t\u201cLa prima edizione del progetto \u2013 sottolinea la presidente della Fondazione, <strong>Marina Pittini<\/strong> \u00ad\u2013 ha coinvolto 22 giovani provenienti da 9 regioni italiane diverse, 10 imprese partner e ha offerto l\u2019erogazione di oltre 90 ore di attivit\u00e0 e formazione gratuita. La call di selezione che lanciamo \u2013 continua Pittini, ricordando la data ultima per la ricezione delle domande, <strong>domenica 22 gennaio 2023<\/strong> \u2013 intende selezionare un gruppo di giovani under 30 desiderosi di intraprendere insieme a noi questo ambizioso percorso: un\u2019esplorazione collettiva attraverso la conoscenza di luoghi e attivit\u00e0 imprenditoriali, culturali e di comunit\u00e0, un tentativo di connessione tra generazioni, professionalit\u00e0 e scelte di vita\u201d.<\/p>\n<p> \t\u201cPercorsi spericolati\u201d nasce in risposta ad alcuni bisogni emersi dalla <a href=\"https:\/\/fondazionepittini.it\/wp-content\/uploads\/2021\/09\/Report-di-ricerca_InnovatoriSocialidellaMontagnaFriulana.pdf\" target=\"_blank\" rel=\"noopener\">ricerca<\/a> sugli imprenditori e sulle imprenditrici delle aree interne e della montagna friulana che la Fondazione ha commissionato nel 2020 al professor <strong>Giovanni Carrosio<\/strong> dell\u2019Universit\u00e0 degli Studi di Trieste e a <strong>Vanni Treu<\/strong> della Cooperativa Sociale Cramars di Tolmezzo.<\/p>\n<p> \tL\u2019indagine ha prodotto un censimento degli imprenditori resilienti di queste aree del Friuli, racchiuse a nord dalle <strong>Dolomiti Friulane<\/strong>, dalla <strong>Carnia<\/strong>, dal <strong>Canal del Ferro<\/strong> e a est dai monti delle <strong>Valli del Natisone<\/strong>, restituendo una fotografia dei bisogni e delle caratteristiche del vivere e lavorare in montagna, con tratti molto comuni alle altre Aree Interne nazionali individuate dalla Strategia Nazionale (SNAI).<\/p>\n<p> \t\u201cIn linea con la missione della Fondazione di valorizzare realt\u00e0 innovative e nuove forme di ri-attivazione dei territori al margine, come quelli mappati e di sostenere al contempo l\u2019empowerment delle nuove generazioni \u2013 conclude Pittini \u2013 il progetto prevede un percorso di formazione multidisciplinare su alcune competenze chiave per imparare a promuovere e valorizzare le singole realt\u00e0 e i territori. L&#8217;esplorazione continua con l&#8217;attivazione di processi di ascolto e poi di valorizzazione delle realt\u00e0 imprenditoriali, artigianali e culturali locali per individuare risposte innovative ai loro bisogni e desideri emergenti\u201d.<\/p>\n<p> \tLa call di selezione \u00e8 rivolta ai giovani di tutta Italia, con et\u00e0 tra i 18 e i 30 anni circa, impegnati ancora negli studi o in cerca di lavoro, appassionati del mondo della montagna e delle aree interne, interessati ai temi della rigenerazione territoriale, con il desiderio di approfondire i linguaggi e le potenzialit\u00e0 dei social media e degli strumenti di comunicazione e racconto (comunicazione, storytelling, social media management, progettazione, service design, community engagement).<\/p>\n<p> \tPer partecipare alla selezione, \u00e8 necessario <strong><u><a href=\"https:\/\/www.percorsispericolati.it\/partecipa\" target=\"_blank\" rel=\"noopener\"><span style=\"color:#0000cd;\">compilare il questionario online<\/span><\/a><\/u> allegando anche il CV <\/strong><strong>entro il 22 gennaio 2023. <\/strong>I risultati della selezione saranno comunicati entro l\u2019inizio di febbraio 2023.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al via la call di selezione nazionale del progetto promosso dalla Fondazione Pietro Pittini rivolto ai giovani under 30<\/p>\n","protected":false},"author":28,"featured_media":48100,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-48099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",1000,750,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",1000,750,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",1000,750,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-300x225.webp",300,225,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",640,480,false],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-300x300.webp",300,300,true],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-500x500.webp",500,500,true],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-474x324.webp",474,324,true],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-391x260.webp",391,260,true],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-300x400.webp",300,400,true],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",1000,750,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",1000,750,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-1000x720.webp",1000,720,true],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",1000,750,false],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",250,188,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/02\/51404-1.webp",243,182,false]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/attualita\/\" rel=\"category tag\">ATTUALIT\u00c0<\/a>","rttpg_excerpt":"Al via la call di selezione nazionale del progetto promosso dalla Fondazione Pietro Pittini rivolto ai giovani under 30","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/48099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=48099"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/48099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/48100"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=48099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=48099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=48099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}