{"id":44477,"date":"2022-08-30T00:00:00","date_gmt":"2022-08-29T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/?p=44477"},"modified":"2022-08-30T00:00:00","modified_gmt":"2022-08-29T23:00:00","slug":"grado-la-carica-degli-800-per-il-triathlon","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/grado-la-carica-degli-800-per-il-triathlon\/","title":{"rendered":"Grado, la carica degli 800 per il Triathlon"},"content":{"rendered":"<p> \tProvengono da sei Stati (Slovenia, Austria, Germania, Svizzera e Svezia oltre che dalla penisola, e da 11 regioni italiane comprese Sicilia e Valle d\u2019Aosta): saranno complessivamente 800 i partecipanti nel fine settimana a <strong>Grado<\/strong> al Triathlon Olimpico no-draft e al Triathlon Sprint promossi con il marchio <strong>Let\u2019s Go Triathlon<\/strong> dal <strong>Circolo Sportivo Adria Gorizia Triathlon<\/strong>.<\/p>\n<p> \tPer l\u2019esattezza il tradizionale <strong>Olimpico no-draft <\/strong>in programma<strong> sabato 3 <\/strong>ha raggiunto il sold out con 570 iscritti (di cui 90 donne), mentre 227 saranno ai nastri di partenza per la gara su distanza <strong>Sprint domenica 4 <\/strong>(di cui 59 donne). Una doppia sfida che consentir\u00e0 di immergersi nelle bellezze di Grado e della sua laguna, dato che secondo la formula collaudata i percorsi si snoderanno tra la spiaggia, i dintorni dell\u2019Isola del sole e il centro storico.<\/p>\n<p> \tTutti gli atleti potranno registrarsi e ritirare il pacco gara gi\u00e0 venerd\u00ec 3, dalle 18 alle 20, nella segreteria gara nella piazzetta del Parco delle Rose, che sar\u00e0 ancora una volta il cuore pulsante della manifestazione.<\/p>\n<p> \tL\u2019edizione 2022 del Triathlon di Grado potr\u00e0 vantare sabato 3 la presenza di un testimonial d\u2019eccezione: il 26enne goriziano <strong>Francesco Ippolito<\/strong>, stella internazionale del nuoto per salvamento dopo i recenti trionfi ai World Games negli Stati Uniti, dove ha conquistato un oro e cinque argenti. L\u2019atleta della Gorizia Nuoto detiene inoltre il record del mondo assoluto nei 100 metri percorso misto e il record italiano assoluto nei 50 metri trasporto manichino.<\/p>\n<p> \t<u><a href=\"http:\/\/www.imagazine.it\/eventi\/41725\" target=\"_blank\" rel=\"noopener\"><span style=\"color:#0000cd;\">Ecco il programma completo dell\u2019evento con le modifiche alla viabilit\u00e0<\/span><\/a><\/u><\/p>\n<p> \t\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Provenienti da sei Paesi europei<\/p>\n","protected":false},"author":28,"featured_media":44478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[38],"tags":[],"class_list":["post-44477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",1600,941,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",1600,941,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",1600,941,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1-300x176.webp",300,176,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1-1024x602.webp",640,376,true],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",300,176,false],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",500,294,false],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",474,279,false],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",391,230,false],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",300,176,false],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1-1536x903.webp",1536,903,true],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",1600,941,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1-1280x720.webp",1280,720,true],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1-1024x602.webp",1024,602,true],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1.webp",250,147,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/49406-1-272x182.webp",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/sport\/\" rel=\"category tag\">SPORT<\/a>","rttpg_excerpt":"Provenienti da sei Paesi europei","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/44477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=44477"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/44477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/44478"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=44477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=44477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=44477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}