{"id":40481,"date":"2021-10-06T00:00:00","date_gmt":"2021-10-05T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/?p=40481"},"modified":"2021-10-06T00:00:00","modified_gmt":"2021-10-05T23:00:00","slug":"monfalcone-senso-unico-in-via-santanna","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/monfalcone-senso-unico-in-via-santanna\/","title":{"rendered":"Monfalcone, senso unico in via Sant&#8217;Anna"},"content":{"rendered":"<p> \tI lavori di riqualificazione di <strong>via Sant\u2019Anna a Monfalcone<\/strong> stanno per concludersi e nella giornata odierna verr\u00e0 apposta la nuova segnaletica verticale che indicher\u00e0 il senso unico con ingresso da via Boito e uscita in via Valentinis.<\/p>\n<p> \tLa segnaletica apposta verr\u00e0 coperta per qualche giorno, in attesa del completamento anche delle strisce pedonali e della segnaletica orizzontale, ma con venerd\u00ec entrer\u00e0 in funzione.<\/p>\n<p> \t\u201cIl senso unico ci \u00e8 stato richiesto per motivi di sicurezza, da parte dei Carabinieri e dei Vigili del fuoco, onde evitare che i mezzi di soccorso si trovassero ostacolati da altre auto sul percorso\u201d, ha precisato il sindaco <strong>Anna Maria Cisint<\/strong>.<\/p>\n<p> \tLa nuova viabilit\u00e0 prevede l&#39;unico ingresso da via Boito e uscita obbligatoria in via Valentinis; anche chi proviene da via San Giacomo sar\u00e0 obbligato a girare a sinistra in direzione Valentinis.\u00a0<\/p>\n<p> \tI lavori di riqualificazione di via Sant\u2019Anna erano iniziati nel mese di maggio, nel tratto compreso tra il Comando della Compagnia dei Carabinieri e l\u2019incrocio con via Boito, per proseguire oltre la SS14 verso il Canale Valentinis.<\/p>\n<p> \t\u201cLa sistemazione di questa via si inserisce in un progetto pi\u00f9 ampio di sistemazione di diverse strade urbane, come via Desena, via Parini e via Marziale \u2013 sottolinea Cisint \u2013 per interventi complessivi di 8 milioni di euro a cui abbiamo aggiunto altri 500 mila euro nell\u2019ultima variazione di bilancio a completamento del ripristino stradale fino a fine mandato\u201d.<\/p>\n<p> \tVerr\u00e0 completato anche il collegamento ciclabile dalla stazione verso la SS14, a servizio anche del vicino Istituto ISIS Pertini. L\u2019ultimo passaggio riguarder\u00e0 infine la connessione ciclabile con la FVG 2 presente sul canale Valentinis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da venerd\u00ec cambia la circolazione<\/p>\n","protected":false},"author":28,"featured_media":40482,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-40481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",2000,1500,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",2000,1500,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",2000,1500,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1-300x225.webp",300,225,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1-1024x768.webp",640,480,true],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",300,225,false],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",500,375,false],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",432,324,false],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",347,260,false],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",300,225,false],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1-1536x1152.webp",1536,1152,true],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",2000,1500,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1-1280x720.webp",1280,720,true],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1-1024x768.webp",1024,768,true],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1.webp",250,188,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/43536-1-272x182.webp",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/attualita\/\" rel=\"category tag\">ATTUALIT\u00c0<\/a>","rttpg_excerpt":"Da venerd\u00ec cambia la circolazione","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/40481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=40481"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/40481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/40482"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=40481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=40481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=40481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}