{"id":33138,"date":"2020-04-20T00:00:00","date_gmt":"2020-04-19T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/?p=33138"},"modified":"2020-04-20T00:00:00","modified_gmt":"2020-04-19T23:00:00","slug":"come-sara-lo-sport-per-disabili-dopo-il-coronavirus","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/come-sara-lo-sport-per-disabili-dopo-il-coronavirus\/","title":{"rendered":"Come sar\u00e0 lo sport per disabili dopo il Coronavirus?"},"content":{"rendered":"<p>In ebollizione anche il baseball che sta pensando come ripartire. Non \u00e8 facile per lo Staranzano BXC (Baseball per ciechi) organizzare sia gli allenamenti sia le gare.<\/p>\n<p>I massimi esponenti della F.I.B.S. (Federazione Italiana Baseball e Softball) e LIBCI (Lega Italiana Baseball Ciechi ed Ipovedenti) e i responsabili delle squadre militanti nel campionato BXC ha tenuto un video-incontro a riguardo.<\/p>\n<p>Se per le serie A1, A2 e B del baseball normodotati e del softball esiste una bozza di previsione di inizio campionati, per BXC ci sono comunque ulteriori problemi da risolvere prima di poter dire se e quando si inizier\u00e0 a giocare. \u00c8 da sottolineare infatti che i giocatori non percepiscono la distanza di uno o pi\u00f9 metri tra i compagni, e che \u00e8 impossibile farli giocare con guanti e\/o mascherine che andrebbero a limitare ulteriormente la loro prestazione, mentre sarebbe altrettanto impossibile per il giocatore vedente in seconda base chiamare la pallina con il classico grido &#8220;due &#8211; due &#8211; due&#8221;, cos\u00ec come sarebbe impossibile per il manager dirigere il gioco dei suoi uomini.<\/p>\n<p>Altro punto \u00e8 la questione igienica e degli spogliatoi: come poter garantire la distanza di un metro fra i giocatori nel momento della preparazione in spogliatoio e durante la doccia? C\u2019\u00e8 l\u2019ipotesi che la squadra di casa possa rientrare subito cos\u00ec da dimezzare il problema, ma anche questa ipotesi non \u00e8 applicabile, in quanto ci sono compagini come l\u2019A.S.D. STARANZANO BXC con giocatori provenienti dalle provincie di Udine e Trieste, senza tralasciare il problema del trasporto allo stadio.<\/p>\n<p>Un\u2019altra ipotesi espressa \u00e8 quella di una nuova formula di campionato in due gironi, da disputare tra qualche fine settimana, riducendo gli inning, forse sacrificando pure alcuni appuntamenti nazionali.<\/p>\n<p>Per far comprendere quanto sia complicato per i giocatori disabili visivi riprendere l&#39;attivit\u00e0 agonistica di questo sport, oltre alle considerazioni sopra esposte si deve far notare che il campionato BXC ha il 40% di formazioni provenienti dalla Lombardia, Brescia compresa, per cui non \u00e8 pensabile scendere in campo fintantoch\u00e9 la situazione dei contagi non sar\u00e0 definitivamente chiusa.<\/p>\n<p>Si \u00e8 gi\u00e0 annunciata l\u2019ipotesi della sospensione della &#8220;Mole&#39;s Cup&#8221; che quest&#39;anno si dovrebbe svolgere in Germania, per la quale rimangono in lizza le formazioni europee, dal momento che Pakistan, USA e Cuba hanno gi\u00e0 disdetto l&#39;appuntamento. Comunque ogni decisione finale \u00e8 rimandata al 15 maggio nella riunione ufficiale con WBSC.<\/p>\n<p><a href=\"http:\/\/imagazinevideotruck.it\/outlet\/relink_imprinta.html\" target=\"_top\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" align=\"LEFT\" height=\"250\" src=\"http:\/\/imagazinevideotruck.it\/outlet\/imprinta.jpg\" width=\"300\" alt=\"\" title=\"\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Al momento questa \u00e8 la situazione del baseball per ciechi ed ipovedenti; si dovr\u00e0 aspettare l&#39;evolversi di questa pandemia prima di poter dire qualcosa di definitivo, nel mentre la societ\u00e0 A.S.D. Staranzano BXC lavora per essere pronti a ogni eventualit\u00e0 qualora si presentassero novit\u00e0 di rilievo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il problema delle distanze di sicurezza<\/p>\n","protected":false},"author":22,"featured_media":33139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[38],"tags":[],"class_list":["post-33138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",750,501,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",750,501,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",750,501,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1-300x200.webp",300,200,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",640,428,false],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",300,200,false],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",500,334,false],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",474,317,false],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",389,260,false],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",300,200,false],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",750,501,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",750,501,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",750,501,false],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",750,501,false],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1.webp",250,167,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33656-1-272x182.webp",272,182,true]},"rttpg_author":{"display_name":"Livio Nonis","author_link":"https:\/\/imagazine.it\/home_desk\/author\/nonis\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/sport\/\" rel=\"category tag\">SPORT<\/a>","rttpg_excerpt":"Il problema delle distanze di sicurezza","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/33138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=33138"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/33138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/33139"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=33138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=33138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=33138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}