{"id":32707,"date":"2020-03-13T00:00:00","date_gmt":"2020-03-12T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/?p=32707"},"modified":"2020-03-13T00:00:00","modified_gmt":"2020-03-12T23:00:00","slug":"export-cresce-la-provincia-di-udine-ma-ormai-e-gia-storia","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/export-cresce-la-provincia-di-udine-ma-ormai-e-gia-storia\/","title":{"rendered":"Export, cresce la provincia di Udine. Ma ormai \u00e8 gi\u00e0 storia"},"content":{"rendered":"<p>Le <strong>esportazioni <\/strong>della provincia di Udine nel <strong>2019<\/strong> sono cresciute in <strong>media d\u2019anno<\/strong> del <strong>3%<\/strong> (da 6.036 a 6.215 milioni di euro). Un aumento in misura inferiore rispetto al <strong>2018<\/strong>, <strong>+ 10,4%<\/strong>, a seguito del calo registrato nel <strong>quarto trimetre<\/strong>, <strong>&#8211; 5,7%<\/strong>.<\/p>\n<p>Nel dettaglio, l\u2019export udinese &#8211; secondo le elaborazioni dell\u2019Ufficio studi di Confindustria su dati Istat &#8211; dopo aver registrato un aumento medio del 7,8% nel primo semestre 2019 e aver decelerato nel terzo, + 2,5%, ha subito una decisa battuta d\u2019arresto nel quarto, &#8211; 5,7%.<\/p>\n<p><strong>La media annua del 2019 delle esportazioni della Provincia di Udine si \u00e8, comunque, mantenuta superiore a quella segnata nel<\/strong> <strong>Nord Est<\/strong> <strong>e in Italia<\/strong> (entrambe + 2,3%). Il <strong>valore complessivo delle esportazioni<\/strong>, come gi\u00e0 nell\u2019anno precedente, \u00e8 <strong>al di sopra di quello pre-crisi<\/strong> (5.861 milioni nel 2008).<\/p>\n<p>La<strong> quota<\/strong> <strong>dell\u2019export udinese su quello regionale<\/strong> (in FVG si \u00e8 registrato un leggero calo nel 2019, -0,8%, imputabile principalmente alla <strong>cantieristica &#8211; 20,9%<\/strong>; <strong>senza <\/strong>tale comparto si registra una crescita del <strong>2,4%<\/strong>), <strong>si \u00e8 attestata al<\/strong> <strong>40,4%<\/strong>, superiore a quella delle altre province (Pordenone 25,8%, Trieste 22,9%, Gorizia 10,9%), <strong>e in crescita rispetto al 2018 (38,9%).<\/strong><\/p>\n<p>La <strong>bilancia commerciale udinese<\/strong> si mantiene sempre positiva, pari a 2.764 milioni di euro, <strong>in crescita del 18,9% rispetto al 2018<\/strong>, a seguito anche del <strong>calo delle<\/strong> <strong>importazioni<\/strong> (-7%, da 3.711 a 3.451 milioni di euro).<\/p>\n<p><a href=\"http:\/\/imagazinevideotruck.it\/outlet\/relink.html\" target=\"_top\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" align=\"LEFT\" height=\"250\" src=\"http:\/\/imagazinevideotruck.it\/outlet\/outlet30.gif\" width=\"300\" alt=\"\" title=\"\"><\/a><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u201cQuesti dati sono storia \u2013 afferma <strong>Anna Mareschi Danieli<\/strong>, presidente di Confindustria \u2013. Di fatto, siamo entrati in un\u2019altra era dopo l\u2019emergenza Coronavirus e ci arriviamo gi\u00e0 in una situazione di rallentamento economico e di debolezza. Per questa ragione non riesco a pensare alla chiusura delle imprese. Sarebbe qualcosa di drammatico. Serve pi\u00f9 senso di responsabilit\u00e0 da parte di tutti i<br \/> cittadini. Tutti dobbiamo osservare in modo rigoroso le disposizioni del Governo. Non c\u2019\u00e8 altra strada per scongiurare l\u2019adozione di misure pi\u00f9 stringenti, che avrebbero conseguenze ancor pi\u00f9 disastrose per il nostro futuro. Perch\u00e9 un futuro ci sar\u00e0 e bisogner\u00e0 arrivarci in piena salute fisica e, possibilmente, in sufficiente salute economica\u201d.<\/p>\n<p>\u201cPer questo \u2013 aggiunge la presidente \u2013 oltre alle misure di contenimento sanitario \u00e8 importante che si faccia presto per adottare anche tutte le misure necessarie a sostenere le imprese. I provvedimenti necessari sono noti. Intanto, siamo alle prese con difficolt\u00e0 enormi su tutti i fronti, ci chiudono i confini e i nostri competitor internazionali non ci fanno sconti. Tutti gli sforzi che le imprese italiane stanno attuando in queste settimane per continuare a produrre e a non bloccare l&#39;economia, osservando regole ferree per la sicurezza sanitaria, vengono letteralmente distrutti da pseudo-misure di prevenzione strumentali e opportunistiche, come ad esempio il blocco austriaco sul transito autostradale del Brennero. Difficolt\u00e0, pi\u00f9 o meno pesanti, si segnalano anche ai confini della Slovenia e della Croazia, solo per citare due esempi a noi pi\u00f9 prossimi. Prodotti deperibili e freschi non vengono consegnati in tempo e rischiano di essere inutilizzabili. Mancate consegne di manufatti necessari ad alimentare le catene industriali rischiano di far chiudere le imprese. Il blocco dei trasporti italiani verso il nord e l\u2019est Europa sta causando danni incalcolabili per il nostro export e per gli scambi europei. Le nostre imprese rischiano di essere escluse dalle catene produttive europee di numerosi settori industriali e tutto questo non potr\u00e0 che peggiorare ulteriormente la crisi economica generata dall&#39;emergenza sanitaria. Questa \u00e8 la situazione. Il nostro Governo si faccia sentire. L\u2019Europa, se c\u2019\u00e8, faccia altrettanto<em>\u201d.<\/em><\/p>\n<p>Tornando ai dati dell\u2019export provinciale, l\u2019incremento delle vendite all\u2019estero, nonostante la diminuzione dei prodotti della <strong>metallurgia<\/strong> (- 10,3%, da 1.787 a 1.603 milioni di euro), prodotti in <strong>metallo<\/strong> (- 4,8%, da 621 a 591 milioni di euro), <strong>mobili<\/strong> (- 3,5%, da 484 a 467 milioni di euro) ed <strong>elettronica e apparecchiature elettriche<\/strong> (- 2,3%, da 404 a 394 milioni di euro),\u00a0 \u00e8 dipeso dai risultati positivi dei <strong>macchinari<\/strong> (+ 28,8%, da 1.158 a 1.492 milioni di euro), articoli in <strong>gomma e materie plastiche<\/strong> (+ 7,6%, da 236 a 254 milioni di euro) e prodotti <strong>chimic<\/strong>i (+ 10,3%, da 173 a 191 milioni di euro). Stazionarie le esportazioni di <strong>prodotti alimentari<\/strong> (+ 0,2%, 261 milioni di euro),\u00a0<\/p>\n<p>L\u2019analisi per mercato di sbocco evidenzia che la <strong>Germania<\/strong>, primo paese di destinazione dell\u2019export con una quota pari al 15,8% del totale (in calo rispetto al 2018, 17,3%), ha registrato nel 2019 una diminuzione del &#8211; 5,7%, da 1.044 a 985 milioni di euro. Il rallentamento dell\u2019economia tedesca, dunque, si \u00e8 gi\u00e0 fatto sentire.<\/p>\n<p>Seguono <strong>Stati Uniti<\/strong> (+ 21,6%, da 434 a 528 milioni di euro),<strong> Austria<\/strong> (- 14,7%), <strong>Francia <\/strong>(+ 3,1%), Spagna (+ 17,8%) e Regno Unito (- 0,9%). In forte aumento le esportazioni in <strong>Cina<\/strong> (+ 34,4%), settimo Paese per destinazione, grazie soprattutto al contributo delle vendite di macchinari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>+ 3% nel 2019<\/p>\n","protected":false},"author":28,"featured_media":32708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-32707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",750,489,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",750,489,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",750,489,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1-300x196.webp",300,196,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",640,417,false],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",300,196,false],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",500,326,false],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",474,309,false],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",391,255,false],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",300,196,false],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",750,489,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",750,489,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",750,489,false],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",750,489,false],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1.webp",250,163,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/33262-1-272x182.webp",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/attualita\/\" rel=\"category tag\">ATTUALIT\u00c0<\/a>","rttpg_excerpt":"+ 3% nel 2019","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/32707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=32707"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/32707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/32708"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=32707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=32707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=32707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}