{"id":22963,"date":"2017-03-21T00:00:00","date_gmt":"2017-03-20T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/?p=22963"},"modified":"2017-03-21T00:00:00","modified_gmt":"2017-03-20T23:00:00","slug":"defibrillatore-300-cittadini-formati-per-lutilizzo","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/defibrillatore-300-cittadini-formati-per-lutilizzo\/","title":{"rendered":"Defibrillatore, 300 cittadini formati per l&#8217;utilizzo"},"content":{"rendered":"<p>In provincia di Pordenone sono oltre duecento le persone all\u2019anno colpite da arresto cardiocircolatorio, in aiuto delle quali si pu\u00f2 intervenire aumentando la percentuale di cittadini formati per compiere manovre di primo intervento e utilizzare il defibrillatore in attesa dell\u2019arrivo della squadra di soccorso: nei giorni in cui sta per debuttare il numero unico regionale di emergenza 112 al posto del \u201cvecchio\u201d 118, diventa sempre pi\u00f9 fondamentale la staffetta tra cittadini e sanitari, come sottolineato da <strong>Claudio Deiuri<\/strong>, direttore del Centro studi e formazione della Gymnasium Pordenone e formatore Irc Comunit\u00e0 a Casarsa della Delizia durante l\u2019incontro che al ridotto del teatro Pasolini ha avviato il progetto \u201cAbbiamo a cuore il tuo cuore\u201d di Friulovest Banca e della sua mutua Credima. Un\u2019iniziativa pilota a livello nazionale che punta a creare un\u2019ampia rete di Comuni cardioprotetti (24 quelli che hanno aderito) attraverso la donazione di defibrillatori e l\u2019organizzazione di incontri formativi.<\/p>\n<p>E proprio Casarsa della Delizia \u00e8 il primo tassello di questo mosaico: a gennaio \u00e8 stato installato in piazza Italia in un luogo accessibile a tutti il defibrillatore donato da Friulovest Banca. Un macchinario di ultima generazione e telecontrollato: una volta staccato dalla sua colonnina si connette autonomamente con i numeri di emergenza e nello stesso tempo con una serie di comandi vocali guida i soccorritori nelle prime manovre, rilevando l&#39;assenza o meno di battito cardiaco e provvedendo autonomamente alla scarica. Questi moderni defibrillatori sopportano anche i cambi di temperatura senza avere decadimenti nelle loro funzionalit\u00e0: prossimamente ne sar\u00e0 installato uno anche nella piazza di San Giovanni di Casarsa.<\/p>\n<p>Dodici tra associazioni e cooperative locali sono state coinvolte nella serata di formazione, mentre sono gi\u00e0 300 i cittadini formati dal Comune di Casarsa della Delizia, che sostiene il progetto insieme all\u2019Azienda sanitaria n.5 del Friuli Occidentale. Numeri che si punta a far crescere.<\/p>\n<p>\u201cIn Italia &#8211; ha aggiunto Deiuri &#8211; abbiamo una maggiore incidenza di morti per arresto cardiocircolatorio rispetto per esempio al Nord Europa ma non perch\u00e9 vi siano pi\u00f9 casi, al contrario, ma perch\u00e9 in quei Paesi il 60-70% della popolazione \u00e8 formata su quali manovre effettuare per intervenire immediatamente. Da noi invece solo il 10% degli astanti, le persone che assistono a un arresto cardiocircolatorio, sa cosa fare: una percentuale che con la nostra attivit\u00e0 di formazione vogliamo aumentare, a partire dalla formazione delle giovani generazioni\u201d.<\/p>\n<p>\u201cUn\u2019azione concreta per la salute e la vita &#8211; ha dichiarato <strong>Vinicio Milan<\/strong> vicepresidente di Friulovest Banca e presidente di Credima -. Pi\u00f9 ampia sar\u00e0 l\u2019area cardioprotetta e pi\u00f9 persone formate ci saranno, pi\u00f9 saremo sicuri tutti\u201d.<\/p>\n<p>Nel corso della serata, moderata da <strong>Markus Maurmair<\/strong>, \u00e8 intervenuto anche l\u2019assessore allo sport di Casarsa della Delizia <strong>Paolo Lamanna<\/strong>. \u201cRingraziamo Friulovest Banca &#8211; ha spiegato &#8211; anche per il primo defibrillatore che ci aveva donato un paio di anni fa e che abbiamo utilizzato nelle strutture sportive: grazie all\u2019operato dell\u2019amministrazione comunale, in cui oltre alla sindaca Lavinia Clarotto ha creduto molto nel progetto il vicesindaco Fernando Agrusti, sempre pi\u00f9 persone sanno come intervenire e utilizzare il defibrillatore. Solamente nel settore sportivo sono gi\u00e0 100 i cittadini formati. Dopo Casarsa a breve un defibrillatore sar\u00e0 installato anche nella piazza di San Giovanni\u201d.<\/p>\n<p>Dodici le associazioni e cooperative locali che hanno aderito al progetto: Il Piccolo Principe, Andi, Quelli della Notte, Osservatorio sociale, Aido, Ana, Avis, Croce rossa, Il Noce, Pro Casarsa della Delizia, Laluna e Associazione famiglie diabetici della provincia di Pordenone.<\/p>\n<p>Al progetto \u201cAbbiamo a cuore il tuo cuore\u201d oltre a Casarsa della Delizia hanno aderito nel Friuli occidentale Castelnovo del Friuli, Cordenons, Cordovado, Sequals, Maniago, Meduno, Montereale Valcellina, Pinzano al Tagliamento, Pordenone, San Giorgio della Richinvelda, San Martino al Tagliamento, San Vito al Tagliamento, Sesto al Reghena, Spilimbergo, Tramonti di Sotto, Travesio, Vajont, Valvasone Arzene, Vivaro e Zoppola e nella Sinistra Tagliamento Codroipo e Forgaria nel Friuli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;esperienza di Casarsa della Delizia<\/p>\n","protected":false},"author":28,"featured_media":22964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-22963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",750,500,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",750,500,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",750,500,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1-300x200.webp",300,200,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",640,427,false],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",300,200,false],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",500,333,false],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",474,316,false],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",391,260,false],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",300,200,false],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",750,500,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",750,500,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",750,500,false],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",750,500,false],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1.webp",250,167,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/18517-1-272x182.webp",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/attualita\/\" rel=\"category tag\">ATTUALIT\u00c0<\/a>","rttpg_excerpt":"L'esperienza di Casarsa della Delizia","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/22963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=22963"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/22963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/22964"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=22963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=22963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=22963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}