{"id":22470,"date":"2017-01-23T00:00:00","date_gmt":"2017-01-22T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/?p=22470"},"modified":"2017-01-23T00:00:00","modified_gmt":"2017-01-22T23:00:00","slug":"le-regate-ditalia-spinte-dal-vento-della-barcolana","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/le-regate-ditalia-spinte-dal-vento-della-barcolana\/","title":{"rendered":"Le regate d&#8217;Italia spinte dal vento della Barcolana"},"content":{"rendered":"<p>Sar\u00e0 di stanza a Trieste, alla Societ\u00e0 Velica di Barcola e Grignano, ma disponibile per eventi su tutto il territorio italiano, una flotta nuova di zecca di scafi J70, una delle imbarcazioni di maggior successo a livello mondiale, ai vertici delle classifiche di vendita.<\/p>\n<p>Barcolana srl &#8211; la societ\u00e0 che commercializza l\u2019omonimo evento per conto della Societ\u00e0 Velica di Barcola e Grignano &#8211; si \u00e8 aggiudicata infatti il ruolo di gestore e manutentore della flotta di J70 di propriet\u00e0 della LegaVela Servizi. Gli scafi saranno utilizzati per le tappe nazionali della Lega Italiana Vela e, per il resto della stagione, saranno a disposizione di equipaggi, circoli velici e aziende che vorranno utilizzarli, singolarmente o in flotta, per regatare e organizzare eventi in tutta Italia.<\/p>\n<p>La flotta di J70 sar\u00e0 gestita anche con soluzioni HBO (HandBag Only) acronimo che definisce una formula particolarmente conveniente per i velisti, che prevede un servizio \u201cchiavi in mano\u201d per quanto riguarda tutti gli aspetti logistici, di manutenzione, gestione e organizzazione relativi allo scafo. Un servizio che permette all\u2019equipaggio di concentrarsi solo sulla regata e veder gestiti e risolti tutti gli aspetti organizzativi a terra e in mare.<\/p>\n<p><em>\u201cUna scelta che abbiamo fatto<\/em>\u00a0&#8211;\u00a0dichiara il presidente di Legavela Servizi Srl, <strong>Alessandro M. Rinaldi<\/strong>\u00a0&#8211;\u00a0<em>non solo per venire incontro alle esigenze dei velisti dei nostri Club, che desiderano regatare su barche nuove, moderne, agili e veloci, ma anche per dare la massima garanzia di uniformit\u00e0 nello svolgimento delle regate e preparare i nostri top teams alle selezioni di <\/em><em>Sailing Champions League<\/em><em> che si svolgeranno sugli stessi J70. La Legavela Servizi, in collaborazione con la Societ\u00e0 Velica di Barcola e Grignano, punter\u00e0 a diventare il riferimento per i velisti di monotipo impegnati nelle regate per Club e in quelle di Classe, offrendo una serie di servizi e agevolazioni anche a chi vuole solamente noleggiare una barca per regatare nei Circuiti. Nomi e marchi che la Legavela ha messo in gioco e che sono gi\u00e0 da soli una garanzia di successo\u201d<\/em>.<\/p>\n<p><em>\u201c<\/em><em>Siamo estremamente orgogliosi di aver ottenuto la possibilit\u00e0 di gestire la flotta J70<\/em>\u00a0&#8211;\u00a0ha dichiarato il direttore sportivo Altomare della Svbg, <strong>Dean Bassi<\/strong>, che segue il progetto in prima persona\u00a0&#8211;\u00a0<em>si tratta della seconda flotta italiana di J70 dopo quella avviata la scorsa stagione dallo Yacht club Costa Smeralda a Porto Cervo. Il nostro compito \u00e8 quello di mettere a disposizione di velisti, circoli e aziende, gli scafi, organizzare e sostenere eventi, dare valore alla nostra capacit\u00e0 logistica, organizzativa e nautica. La stessa capacit\u00e0 che ci permette di organizzare ogni anno la Barcolana\u201d<\/em>.<\/p>\n<p>La flotta sar\u00e0 varata nel mese di marzo, in tempo per permettere agli equipaggi che vorranno averle a disposizione di partecipare alla stagione italiana J70 e agli eventi internazionali che la classe organizza quest\u2019anno in Italia, a partire dal campionato mondiale. Le prenotazioni per noleggiare uno o pi\u00f9 imbarcazioni sono gi\u00e0 aperte: per avere informazioni \u00e8 disponibile il sito\u00a0<a data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=it&#038;q=http:\/\/wpcomunicazione.us12.list-manage.com\/track\/click?u%3D5a801981f425f5f8bb1bb7b60%26id%3D376da56e07%26e%3Db9a83ccad4&#038;source=gmail&#038;ust=1485270409718000&#038;usg=AFQjCNFQRCZALAjjz0e_5BWYp0AGRM6QEQ\" href=\"http:\/\/wpcomunicazione.us12.list-manage.com\/track\/click?u=5a801981f425f5f8bb1bb7b60&#038;id=376da56e07&#038;e=b9a83ccad4\" target=\"_blank\" rel=\"noopener\">www.legavelaservizi.it<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In collaborazione con LegaVela Servizi<\/p>\n","protected":false},"author":28,"featured_media":22471,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[38],"tags":[],"class_list":["post-22470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",750,498,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",750,498,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",750,498,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1-300x199.webp",300,199,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",640,425,false],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",300,199,false],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",500,332,false],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",474,315,false],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",391,260,false],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",300,199,false],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",750,498,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",750,498,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",750,498,false],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",750,498,false],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1.webp",250,166,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/17619-1-272x182.webp",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/sport\/\" rel=\"category tag\">SPORT<\/a>","rttpg_excerpt":"In collaborazione con LegaVela Servizi","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/22470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=22470"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/22470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/22471"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=22470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=22470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=22470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}