{"id":19942,"date":"2016-06-17T00:00:00","date_gmt":"2016-06-16T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/?p=19942"},"modified":"2016-06-17T00:00:00","modified_gmt":"2016-06-16T23:00:00","slug":"le-notti-blues-di-gorizia","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/le-notti-blues-di-gorizia\/","title":{"rendered":"Le notti blues di Gorizia"},"content":{"rendered":"<p style=\"text-align: justify;\" class=\"ui-droppable\"> \tUn festival in grado di andare oltre i confini fisici e mentali, superandoli grazie a un programma ricco e originale, tra musica, arte, poesia, incontri e performance innovative: \u00e8 questo il Blue Notte Gorizia Festival 2016 in programma per la sesta volta dal 23 al 25 giugno a Gorizia e a \u0160empeter, in Slovenia, organizzato da Contea Societ\u00e0 Cooperativa Sociale Onlus (Gorizia) con i Comuni di Gorizia e \u0160empeter-Vrtojba, con il sostegno della Regione Autonoma Friuli Venezia Giulia, della Provincia di Gorizia e della Ca.Ri.Go. &#8211; Fondazione Cassa di Risparmio di Gorizia.<\/p>\n<p style=\"text-align: justify;\" class=\"ui-droppable\"> \tIl\u00a0 primo appuntamento \u00e8 a \u0160empeter\u00a0 gioved\u00ec 23 giugno dove, dopo l&#8217;inaugurazione ufficiale alla presenza dei primi cittadini della cittadina slovena e di Gorizia, salir\u00e0 sul palcoscenico<strong> Mike Andersen<\/strong>, alle 21.<\/p>\n<p style=\"text-align: justify;\" class=\"ui-droppable\"> \tAndersen \u00e8 un musicista danese noto in tutto il mondo per la sua capacit\u00e0 di rileggere il blues e il soul per dare vita a un suono ricco di energia e di passione. Gi\u00e0 nel 2005 \u00e8 stato suo il quinto <em>Annual Independent Music Awards<\/em> nella categoria del blues: una conferma doverosa per un musicista che sin dal suo primo album, <em>My love for the blues<\/em>, del 2002, vanta un ruolo di primissimo piano all&#8217;interno della scena nordeuropea.<\/p>\n<p style=\"text-align: justify;\" class=\"ui-droppable\"> \t<strong>Venerd\u00ec 24 giugno<\/strong> Blue Notte si sposter\u00e0 a Gorizia, entrando nel vivo con un percorso suggestivo e avvincente: nel panorama del Parco Basaglia <strong>la manifestazione inaugurer\u00e0 alle 19<\/strong> per lasciare spazio alle 20, a<strong> Gregoire Ahongbonon<\/strong>\u00a0 che racconter\u00e0 della sua missione di liberazione dallo stato di degrado delle persone colpite dal disagio mentale in Africa. Conosciuto come il &#8220;Basaglia Africano&#8221;, Gregoire (con l&#8217;associazione Jobel da lui stesso fondata) \u00e8 ormai un riferimento universale per il rispetto dei diritti dei malati di mente e ha al suo attivo centinaia di persone salvate dalle catene e dal degrado in diversi paesi africani.<\/p>\n<p style=\"text-align: justify;\" class=\"ui-droppable\"> \tAlle 20.30 sar\u00e0 la volta di un progetto del tutto originale,\u00a0 nato in seno a Blue Notte Gorizia Festival:<strong> Klaus Gesing<\/strong> (compositore e ancia di pregio del jazz, di origine tedesca) presenta <strong><em>Sound of Mind,<\/em><\/strong> un&#8217;installazione\/performance audio-visiva (<strong>concepita insieme al light designer Marco Godeas<\/strong>) che con le musiche originali commenter\u00e0 dal vivo il <strong>percorso di Gregoire<\/strong>: un <strong>progetto che accosta suono, fotografia e luce<\/strong>, profondo e di grande senso estetico, per riflettere insieme grazie all&#8217;arte e a nuove dimensioni percettive. Durante la performance, che coinvolger\u00e0 anche alcune delle pi\u00f9 belle immagini fotografiche in mostra, <strong>vengono lette otto poesie (anch&#8217;esse dedicate alla tematica oggetto della mostra), scelte tra quelle pervenute al Primo Concorso Internazionale indetto dal Festival<\/strong> stesso:\u00a0 alla fine della performance vengono anche <strong>decretati i titoli vincitori tra le poesie<\/strong> in concorso, che &#8211; secondo il regolamento &#8211; <strong>riceveranno i previsti premi<\/strong>.<\/p>\n<p style=\"text-align: justify;\" class=\"ui-droppable\"> \t<strong>Alle 21 il vernissage<\/strong> aprir\u00e0 le porte alla toccante mostra fotografica &#8220;Dalle catene alla rinascita&#8221;: si tratta di una rassegna artistica e insieme documentaria dell&#8217;esperienza di <strong>Gregoire, con alcune tra le foto pi\u00f9 significative del suo percorso degli ultimi anni.<\/strong><\/p>\n<p style=\"text-align: justify;\" class=\"ui-droppable\"> \tAlle 21.30, a tenere il palcoscenico sar\u00e0 chiamato invece il<strong> Gesing Roher Meyer Trio<\/strong>, ensemble di artisti che dell&#8217;innovazione hanno fatto da sempre la loro bandiera (ancora capitanati da Klaus Gesing): il superamento dei confini tra improvvisazione, composizione e interpretazione diventa un sound sperimentale, con componenti spaziali e ritmiche quasi visionarie. <strong>Gesing, oltre che arrangiatore, \u00e8 abile clarinettista e sassofonista (clarinetto basso e sax soprano)<\/strong>, Samuel Rohrer \u00e8 alla batteria e Bj\u00f6rn Meyer al basso. <strong>Nel loro lavoro <em>Amiira<\/em><\/strong> (che a Gorizia presentano in prima italiana, e in &#8220;seconda assoluta&#8221; poich\u00e9 la prima si tiene <strong>il 23 giugno in Germania &#8211; al Club Bastion di Kirchheim unter Teck, anch&#8217;essa tappa inserita sotto il &#8220;cappello&#8221; ideale del Festival Blue Notte<\/strong>) sintetizzano la loro grande esperienza musicale, giocando tra jazz, world music, musica cameristica di origine classica, improvvisazione e nuove tecnologie per dare vita a un disco (e a un concerto!) di rara intensit\u00e0.<\/p>\n<p style=\"text-align: justify;\" class=\"ui-droppable\"> \tSabato 25 giugno, sempre nel Parco Basaglia a Gorizia &#8211; dopo una parentesi affettuosa grazie allo spettacolo proposto dai bambini della <strong>scuola dell&#8217;infanzia di Varmo alle 19.30 <\/strong>&#8211; il festival chiuder\u00e0 con una grande festa, che vedr\u00e0 sul palcoscenico i<strong> 24 Pesos <\/strong>(21.30), band inglese dal chiaro stampo blues, irresistibile ed esplosiva, definita attualmente la miglior blues band dello scenario inglese (Maverick Magazine). I 24 Pesos sono insieme dal 2008 e hanno al loro attivo quattro album e una lunga lista di concerti sold out oltre a ben quattro nomination ai British Blues Awards, comprese quella per la miglior band e il miglior album. Proprio nel 2016 la band ha anche vinto il Blues and Soul Show Award for Innovation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal 23 al 25 giugno il Blue Notte Festival<\/p>\n","protected":false},"author":28,"featured_media":19943,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[37],"tags":[],"class_list":["post-19942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-e-spettacolo"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",750,500,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",750,500,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",750,500,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1-300x200.webp",300,200,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",640,427,false],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",300,200,false],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",500,333,false],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",474,316,false],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",391,260,false],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",300,200,false],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",750,500,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",750,500,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",750,500,false],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",750,500,false],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1.webp",250,167,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/14773-1-272x182.webp",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/cultura-e-spettacolo\/\" rel=\"category tag\">CULTURA&amp;SPETTACOLO<\/a>","rttpg_excerpt":"Dal 23 al 25 giugno il Blue Notte Festival","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/19942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=19942"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/19942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/19943"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=19942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=19942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=19942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}