{"id":19407,"date":"2016-03-21T00:00:00","date_gmt":"2016-03-20T23:00:00","guid":{"rendered":"https:\/\/imagazine.it\/?p=19407"},"modified":"2016-03-21T00:00:00","modified_gmt":"2016-03-20T23:00:00","slug":"nuova-sede-per-la-fondazione-pordenonelegge-it","status":"publish","type":"post","link":"https:\/\/imagazine.it\/home_desk\/nuova-sede-per-la-fondazione-pordenonelegge-it\/","title":{"rendered":"Nuova sede per la Fondazione Pordenonelegge.it"},"content":{"rendered":"<p class=\"ui-droppable\" style=\"text-align: justify;\"> \tCompletato il trasferimento della Fondazione Pordenonelegge.it da via del Castello nella nuova sede, al secondo piano di Palazzo Badini, nel cuore di Pordenone (via Mazzini 2).<\/p>\n<\/p>\n<p class=\"ui-droppable\" style=\"text-align: justify;\"> \tDa oggi il motore pulsante di <em>pordenonelegge<\/em>, Festa del Libro con gli Autori (in calendario quest\u2019anno dal 14 al 18 settembre) si accender\u00e0 nel polo turistico e culturale della citt\u00e0, la sede municipale che gi\u00e0 ospita PromoTurismoFVG, Cinemazero e la Mediateca di Pordenone: \u00abProprio da Palazzo Badini, al fianco delle altre realt\u00e0 culturali di riferimento, \u2013 spiega il Presidente <strong>Giovanni Pavan<\/strong> \u2013 la Fondazione Pordenonelegge.it rilancia\u00a0 il suo impegno per traguardi importanti da condividere con la citt\u00e0 e il territorio. Fare squadra \u00e8 presupposto determinante perch\u00e9 i progetti e gli eventi che organizziamo possano avere successo sul territorio, catalizzando anche l\u2019interesse del pubblico, degli operatori, dei media e dei portatori di interesse nazionali e internazionali\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al secondo piano di Palazzo Badini<\/p>\n","protected":false},"author":28,"featured_media":19408,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"dwc-title":[],"dwc-content":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-19407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita"],"rttpg_featured_image_url":{"full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",750,501,false],"landscape":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",750,501,false],"portraits":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",750,501,false],"thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1-150x150.webp",150,150,true],"medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1-300x200.webp",300,200,true],"large":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",640,428,false],"thumblist":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",300,200,false],"thumbrelated":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",500,334,false],"meccarouselthumb":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",474,317,false],"gridsquare":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",389,260,false],"tileview":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",300,200,false],"1536x1536":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",750,501,false],"2048x2048":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",750,501,false],"newsup-slider-full":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",750,501,false],"newsup-featured":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",750,501,false],"newsup-medium":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1-720x380.webp",720,380,true],"tptn_thumbnail":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1.webp",250,167,false],"sow-carousel-default":["https:\/\/imagazine.it\/wp-content\/uploads\/2024\/01\/13409-1-272x182.webp",272,182,true]},"rttpg_author":{"display_name":"redazione","author_link":"https:\/\/imagazine.it\/home_desk\/author\/redazione\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/imagazine.it\/home_desk\/category\/attualita\/\" rel=\"category tag\">ATTUALIT\u00c0<\/a>","rttpg_excerpt":"Al secondo piano di Palazzo Badini","_links":{"self":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/19407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/comments?post=19407"}],"version-history":[{"count":0,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/posts\/19407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media\/19408"}],"wp:attachment":[{"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/media?parent=19407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/categories?post=19407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imagazine.it\/home_desk\/wp-json\/wp\/v2\/tags?post=19407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}